﻿{"id":64750,"date":"2024-05-07T08:30:38","date_gmt":"2024-05-07T06:30:38","guid":{"rendered":"https:\/\/valoxy.org\/blog\/?p=64750"},"modified":"2025-11-14T13:53:22","modified_gmt":"2025-11-14T12:53:22","slug":"la-fresque-du-climat","status":"publish","type":"post","link":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/","title":{"rendered":"La Fresque du climat"},"content":{"rendered":"<p class=\"p4\"><i>\u201cAtelier de sensibilisation aux enjeux du changement climatique\u201d, <\/i>la \u201cFresque du Climat\u201d constitue une approche p\u00e9dagogique qui permet \u00e0 tous d\u2019appr\u00e9hender l\u2019ampleur, mais aussi la complexit\u00e9 des enjeux li\u00e9s aux d\u00e9r\u00e8glements climatiques.<\/p>\n<p class=\"p4\">Accessible au grand public comme aux entreprises, elle est pr\u00e9sent\u00e9e comme<i> \u201cl\u2019outil indispensable pour comprendre l\u2019encha\u00eenement des causes et des effets du r\u00e9chauffement climatique\u201d.<\/i><\/p>\n<p class=\"p4\">Valoxy, cabinet d\u2019expertise comptable dans les Hauts-de-France, en d\u00e9taille l\u2019int\u00e9r\u00eat dans cet article.<\/p>\n<h2 class=\"p6\"><b>Qu\u2019est-ce que la Fresque du Climat ?<\/b><\/h2>\n<p class=\"p7\"><span class=\"s1\"><a href=\"https:\/\/fresqueduclimat.org\/\">La Fresque du Climat<\/a><\/span> est une v\u00e9ritable formation (un \u201catelier\u201d), \u00e0 la fois ludique et p\u00e9dagogique, qui permet de poser en quelques heures les grands principes du r\u00e9chauffement climatique. Cet atelier de sensibilisation s\u2019appuie sur les rapports du<span class=\"Apple-converted-space\">\u00a0 <\/span><a href=\"https:\/\/www.ipcc.ch\/languages-2\/francais\/\"><span class=\"s2\">GIEC<\/span><\/a> (Groupe d\u2019Experts Intergouvernemental sur l\u2019Evolution du Climat), et donc sur un large \u201cconsensus scientifique\u201d sur le sujet.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p7\">Organis\u00e9 en groupe de 5 \u00e0 8 personnes, men\u00e9 par un animateur, (qui peut \u00eatre assist\u00e9 d\u2019un \u201cco-animateur\u201d), parfois en pr\u00e9sence d\u2019un \u201cobservateur\u201d, l\u2019atelier dure 3 heures.<\/p>\n<p class=\"p7\">Une premi\u00e8re \u201cphase\u201d consiste, pour les participants, \u00e0 placer sur une table diff\u00e9rentes\u00a0\u201ccartes\u201d, repr\u00e9sentant chacune un aspect du sujet (\u201cs\u00e9cheresse\u201d, \u201cindustries\u201d, \u201c\u00e9missions de CO<span class=\"s3\"><sub>2<\/sub><\/span>\u201d, \u201cfonte des glaciers\u201d, \u201cpuits de carbone\u201d, \u201cr\u00e9fugi\u00e9s climatiques\u201d, etc.), en fonction de leurs liens entre eux. Le but est de relier toutes ces cartes en constituant un encha\u00eenement (la \u201cFresque\u201d) de causes, d\u2019interactions et de cons\u00e9quences. Au verso des cartes est imprim\u00e9 un texte concis, expliquant ou d\u00e9finissant le sujet illustr\u00e9 au recto.<\/p>\n<p class=\"p7\">L\u2019int\u00e9r\u00eat r\u00e9side \u00e0 laisser les participants trouver eux-m\u00eames les r\u00e9ponses aux questions qu\u2019ils se posent sur ces encha\u00eenements et ces interactions. C\u2019est aussi le moment o\u00f9 l\u2019on cherchera un titre \u00e0 la \u201cfresque\u201d ainsi form\u00e9e.<\/p>\n<p class=\"p7\">Dans l\u2019\u00e9tape suivante, les participants expriment, chacun \u00e0 leur tour, les sentiments qui les animent suite \u00e0 ce qu\u2019ils viennent d\u2019apprendre ou de d\u00e9couvrir.<\/p>\n<p class=\"p7\">Vient enfin une \u201cprise de conscience\u201d, illustr\u00e9e par une r\u00e9flexion sur les solutions \u00e0 mettre en oeuvre, mais aussi les actions (les \u201cr\u00e9solutions\u201d) de chacun. (aller au travail en v\u00e9lo, manger moins de viande, trier ses d\u00e9chets, s\u2019engager en faveur de la lutte contre les in\u00e9galit\u00e9s, r\u00e9parer et ne pas jeter, devenir animateur de \u201cLa Fresque\u201d, etc.).<\/p>\n<p class=\"p7\">A noter que \u201cLa Fresque\u201d existe aussi sous forme de Quiz, plus comp\u00e9titive. Dans cette formule, d\u2019autres sessions, gr\u00e2ce \u00e0 plusieurs tables, stimulent la comp\u00e9tition et la cr\u00e9ativit\u00e9 entre les groupes.<\/p>\n<h2 class=\"p6\"><b>Int\u00e9r\u00eat pour les entreprises<\/b><\/h2>\n<p class=\"p4\">\u00c0 l\u2019instar de Saint Gobain, D\u00e9cathlon, Renault, et beaucoup d\u2019autres, de nombreuses entreprises font appel \u00e0 \u201cLa Fresque du Climat\u201d pour sensibiliser leurs collaborateurs au r\u00e9chauffement climatique. L\u2019int\u00e9r\u00eat de l\u2019outil est qu\u2019il expose clairement, sous forme ludique et participative, les enjeux du changement climatique. (Voir notre article <a href=\"https:\/\/valoxy.org\/blog\/lentreprise-et-la-neutralite-carbone\/\"><span class=\"s4\"><i>L\u2019entreprise et la neutralit\u00e9 carbone<\/i><\/span><\/a><i>). <\/i>Mieux qu\u2019un texte (r\u00e9barbatif), qu\u2019un Powerpoint (passif), ou qu\u2019une formation \u201cclassique\u201d (trop didactique, et sujette aux \u00e0 priori), la Fresque du Climat fait v\u00e9ritablement entrer les participant dans la r\u00e9flexion et le raisonnement\u2026 et donc dans la compr\u00e9hension de ce sujet \u00e9minemment complexe. Les entreprises peuvent :<\/p>\n<ul class=\"ul1\">\n<li class=\"li4\"><i><\/i>mobiliser les salari\u00e9s, qui reviennent souvent de leur \u201dFresque\u201d motiv\u00e9s pour agir, et r\u00e9fl\u00e9chissent \u00e0 ce qu&rsquo;ils peuvent faire dans leur service, \u00e0 leur niveau,<\/li>\n<li class=\"li4\"><i><\/i>faire comprendre des d\u00e9cisions ou des orientations,<\/li>\n<li class=\"li4\"><i><\/i>r\u00e9aliser un guide pratique de leurs actions possibles,<\/li>\n<\/ul>\n<p class=\"p4\">dans un environnement \u00e9conomique qui sera de plus en plus marqu\u00e9 par les cons\u00e9quences du changement climatique.<\/p>\n<h2 class=\"p6\"><b>D\u00e9fauts et points positifs<\/b><\/h2>\n<p class=\"p4\">\u201cLa Fresque du Climat\u201d peut \u00eatre ressentie comme pessimiste, et rendre les participants \u201c\u00e9co-d\u00e9pressifs\u201d. De plus, elle ne propose pas r\u00e9ellement de \u201csolution\u201d. Mais elle offre un temps de r\u00e9flexion, qui cl\u00f4t l\u2019atelier. Les \u00e9changes qui ont lieu entre les participants insistent sur ce qu\u2019ils peuvent faire, \u201cchacun \u00e0 leur niveau\u201d. Le caract\u00e8re collectif de la r\u00e9flexion initi\u00e9e est ainsi un point tr\u00e8s positif. \u201cL\u2019intelligence collective\u201d induite dans la \u201cFresque\u201d gr\u00e2ce aux \u00e9changes est primordiale.<\/p>\n<p class=\"p4\">L\u2019int\u00e9r\u00eat de la \u201cFresque\u201d est aussi de donner envie de comprendre. La Fresque pousse \u00e0 aller voir plus loin les pistes propos\u00e9es par le GIEC, ou amorc\u00e9es par l&rsquo;Accord de Paris. Elle est enfin un outil riche d\u2019arguments face aux climatosceptiques et aux diffuseurs de fausses nouvelles.<\/p>\n<p class=\"p4\">Enfin, il faut aussi noter que ces \u201cjeux de plateau\u00a0\u00bb ont fait beaucoup d&rsquo;\u00e9mules sur des sujets \u201cconnexes\u201d et parall\u00e8les. Ont ainsi vu le jour \u201cLa Fresque des d\u00e9chets\u201d, \u201cLa Fresque de la biodiversit\u00e9\u201d, qui, avec des techniques similaires, sensibilisent \u00e0 d\u2019autres sujets tout aussi importants !<\/p>\n<h2 class=\"p6\"><b>Une prise de conscience croissante<\/b><\/h2>\n<p class=\"p4\">Cr\u00e9\u00e9e en 2018 par C\u00e9dric Ringenbach, ing\u00e9nieur Centrale Nantes, \u00e0 partir des publications du GIEC, \u201cLa Fresque du Climat\u201d est d\u2019abord une association. Elle repose sur un r\u00e9seau d&rsquo;animateurs b\u00e9n\u00e9voles, eux-m\u00eames form\u00e9s par des b\u00e9n\u00e9voles.<\/p>\n<p class=\"p4\">\u201cLa Fresque du Climat\u201d a \u00e9t\u00e9 traduite dans de nombreuses langues, et d\u00e9clin\u00e9e sur tous les continents. Depuis son origine, elle a touch\u00e9 plus d\u2019un million et demi de participants, dont un tiers en entreprise. Les salari\u00e9s peuvent ensuite se former eux-m\u00eames \u00e0 l\u2019animation, et m\u00eame former des formateurs au sein de l\u2019entreprise\u2026<\/p>\n<p class=\"p11\"><span class=\"s6\">Vous voulez agir pour le climat mais n\u2019avez pas le temps de devenir climatologue ? <a href=\"https:\/\/fresqueduclimat.org\/inscription-atelier\/\"><span class=\"s7\">Inscrivez-vous !<\/span><\/a><span class=\"Apple-converted-space\">\u00a0 <\/span>Allez vous sensibiliser \u00e0 une \u201cFresque du Climat\u201d pr\u00e8s de chez vous ! \u201cLa Fresque\u201d permet \u00e0 chacun de comprendre le fonctionnement, l\u2019ampleur et la complexit\u00e9 des enjeux li\u00e9s aux d\u00e9r\u00e8glements climatiques !<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p11\"><span class=\"s6\">Retrouvez aussi nos articles sur le Climat et les enjeux du r\u00e9chauffement climatique :<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li13\"><a href=\"https:\/\/valoxy.org\/blog\/quest-ce-que-les-cop\/\">Qu\u2019est-ce que les COP ?<\/a><\/li>\n<li class=\"li13\"><span class=\"s5\"><a href=\"https:\/\/valoxy.org\/blog\/la-reforme-du-marche-du-carbone\/\"><span class=\"s8\">La r\u00e9forme du march\u00e9 du carbone<\/span><\/a><\/span><\/li>\n<li class=\"li13\"><span class=\"s5\"><a href=\"https:\/\/valoxy.org\/blog\/les-mobilites-durables-verdissent-un-peu-plus\/\"><span class=\"s8\">Les mobilit\u00e9s durables verdissent un peu plus<\/span><\/a><\/span><\/li>\n<li class=\"li13\"><span class=\"s5\"><a href=\"https:\/\/valoxy.org\/blog\/acronymes-de-lentreprise-verte-et-responsable\/\"><span class=\"s8\">Les acronymes de l\u2019entreprise verte et responsable<\/span><\/a><\/span><\/li>\n<li class=\"li13\"><span class=\"s5\"><a href=\"https:\/\/valoxy.org\/blog\/lexique-du-rechauffement-climatique-a-usage-des-entreprises\/\"><span class=\"s8\">Petit lexique du r\u00e9chauffement climatique \u00e0 usage des entreprises<\/span><\/a><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAtelier de sensibilisation aux enjeux du changement climatique\u201d, la \u201cFresque du Climat\u201d constitue une approche p\u00e9dagogique qui permet \u00e0 tous d\u2019appr\u00e9hender l\u2019ampleur, mais aussi la complexit\u00e9 des enjeux li\u00e9s aux d\u00e9r\u00e8glements climatiques. Accessible au grand public comme aux entreprises, elle&#8230;<\/p>\n","protected":false},"author":2,"featured_media":64751,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,4],"tags":[],"class_list":["post-64750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bons-plans-valoxy","category-social-rh"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fresque du climat | Blog Valoxy - Expertise comptable<\/title>\n<meta name=\"description\" content=\"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fresque du climat | Blog Valoxy - Expertise comptable\" \/>\n<meta property=\"og:description\" content=\"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Valoxy - Expertise comptable\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Valoxy\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T06:30:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T12:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2041\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Valoxy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Valoxy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\"},\"author\":{\"name\":\"Blog Valoxy\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/3f71a9f88ba7f93930e05ad0916f879c\"},\"headline\":\"La Fresque du climat\",\"datePublished\":\"2024-05-07T06:30:38+00:00\",\"dateModified\":\"2025-11-14T12:53:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\"},\"wordCount\":1027,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg\",\"articleSection\":[\"Bons plans Valoxy\",\"Social-rh\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\",\"url\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\",\"name\":\"La Fresque du climat | Blog Valoxy - Expertise comptable\",\"isPartOf\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg\",\"datePublished\":\"2024-05-07T06:30:38+00:00\",\"dateModified\":\"2025-11-14T12:53:22+00:00\",\"description\":\"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.\",\"breadcrumb\":{\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage\",\"url\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg\",\"contentUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg\",\"width\":2560,\"height\":2041,\"caption\":\"image de Freepik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/valoxy.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fresque du climat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valoxy.org\/blog\/#website\",\"url\":\"https:\/\/valoxy.org\/blog\/\",\"name\":\"Blog Valoxy\",\"description\":\"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise\",\"publisher\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\"},\"alternateName\":\"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valoxy.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\",\"name\":\"Blog Valoxy\",\"url\":\"https:\/\/valoxy.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png\",\"contentUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png\",\"width\":266,\"height\":100,\"caption\":\"Blog Valoxy\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Valoxy\",\"https:\/\/www.linkedin.com\/company\/valoxy\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/3f71a9f88ba7f93930e05ad0916f879c\",\"name\":\"Blog Valoxy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/37a89ae34ab0a967ba430f960936da1ca59d9882a0d80a7651c5bd8881ea0707?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/37a89ae34ab0a967ba430f960936da1ca59d9882a0d80a7651c5bd8881ea0707?s=96&d=mm&r=g\",\"caption\":\"Blog Valoxy\"},\"url\":\"https:\/\/valoxy.org\/blog\/author\/nikobond\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fresque du climat | Blog Valoxy - Expertise comptable","description":"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/","og_locale":"fr_FR","og_type":"article","og_title":"La Fresque du climat | Blog Valoxy - Expertise comptable","og_description":"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.","og_url":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/","og_site_name":"Blog Valoxy - Expertise comptable","article_publisher":"https:\/\/www.facebook.com\/Valoxy","article_published_time":"2024-05-07T06:30:38+00:00","article_modified_time":"2025-11-14T12:53:22+00:00","og_image":[{"width":2560,"height":2041,"url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg","type":"image\/jpeg"}],"author":"Blog Valoxy","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Blog Valoxy","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#article","isPartOf":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/"},"author":{"name":"Blog Valoxy","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/3f71a9f88ba7f93930e05ad0916f879c"},"headline":"La Fresque du climat","datePublished":"2024-05-07T06:30:38+00:00","dateModified":"2025-11-14T12:53:22+00:00","mainEntityOfPage":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/"},"wordCount":1027,"commentCount":0,"publisher":{"@id":"https:\/\/valoxy.org\/blog\/#organization"},"image":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage"},"thumbnailUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg","articleSection":["Bons plans Valoxy","Social-rh"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/","url":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/","name":"La Fresque du climat | Blog Valoxy - Expertise comptable","isPartOf":{"@id":"https:\/\/valoxy.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage"},"image":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage"},"thumbnailUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg","datePublished":"2024-05-07T06:30:38+00:00","dateModified":"2025-11-14T12:53:22+00:00","description":"La Fresque du climat est une formation et un atelier de sensibilisation qui permet de poser quelques grands principes du r\u00e9chauffement climatique.","breadcrumb":{"@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#primaryimage","url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg","contentUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/fresque-du-climat-scaled-1.jpg","width":2560,"height":2041,"caption":"image de Freepik"},{"@type":"BreadcrumbList","@id":"https:\/\/valoxy.org\/blog\/la-fresque-du-climat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/valoxy.org\/blog\/"},{"@type":"ListItem","position":2,"name":"La Fresque du climat"}]},{"@type":"WebSite","@id":"https:\/\/valoxy.org\/blog\/#website","url":"https:\/\/valoxy.org\/blog\/","name":"Blog Valoxy","description":"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise","publisher":{"@id":"https:\/\/valoxy.org\/blog\/#organization"},"alternateName":"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valoxy.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/valoxy.org\/blog\/#organization","name":"Blog Valoxy","url":"https:\/\/valoxy.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png","contentUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png","width":266,"height":100,"caption":"Blog Valoxy"},"image":{"@id":"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Valoxy","https:\/\/www.linkedin.com\/company\/valoxy"]},{"@type":"Person","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/3f71a9f88ba7f93930e05ad0916f879c","name":"Blog Valoxy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/37a89ae34ab0a967ba430f960936da1ca59d9882a0d80a7651c5bd8881ea0707?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37a89ae34ab0a967ba430f960936da1ca59d9882a0d80a7651c5bd8881ea0707?s=96&d=mm&r=g","caption":"Blog Valoxy"},"url":"https:\/\/valoxy.org\/blog\/author\/nikobond\/"}]}},"_links":{"self":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/64750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/comments?post=64750"}],"version-history":[{"count":2,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/64750\/revisions"}],"predecessor-version":[{"id":72773,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/64750\/revisions\/72773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/media\/64751"}],"wp:attachment":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/media?parent=64750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/categories?post=64750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/tags?post=64750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}