﻿{"id":63832,"date":"2023-10-17T08:30:40","date_gmt":"2023-10-17T06:30:40","guid":{"rendered":"https:\/\/valoxy.org\/blog\/?p=63832"},"modified":"2026-01-27T09:43:37","modified_gmt":"2026-01-27T08:43:37","slug":"dispositifs-fiscaux-de-linvestissement-locatif","status":"publish","type":"post","link":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/","title":{"rendered":"Dispositifs fiscaux de l\u2019investissement locatif"},"content":{"rendered":"<p>De nombreux dispositifs fiscaux de l&rsquo;investissement locatif existent en France. Ils permettent d\u2019optimiser certains investissements immobiliers. Leur objectif\u00a0 ? Utiliser l&rsquo;accession \u00e0 la propri\u00e9t\u00e9 immobili\u00e8re locative pour alimenter (et dynamiser) le march\u00e9 immobilier locatif.<\/p>\n<p>Valoxy, cabinet d\u2019expertise comptable dans les Hauts-de-France, rappelle dans cet article les grandes lignes des dispositifs fiscaux de l&rsquo;investissement locatif.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>Le principe de l&rsquo;investissement locatif<\/strong><\/h2>\n<p>En \u00e9change de l&rsquo;acquisition et de la mise en location sur une p\u00e9riode minimum (9 ans) d&rsquo;un bien immobilier, l\u2019acqu\u00e9reur-investisseur b\u00e9n\u00e9ficie d\u2019un avantage fiscal (d\u00e9duction\u00a0 ou r\u00e9duction). (Voir notre article <a href=\"https:\/\/valoxy.org\/blog\/le-statut-de-bailleur-prive\/\">Le statut de bailleur priv\u00e9<\/a>). Le bien doit en g\u00e9n\u00e9ral \u00eatre mis en location dans les 12 mois \u00e0 compter de la date de fin des travaux, ou de la r\u00e9novation. Le bien doit constituer la r\u00e9sidence principale du locataire, et celui-ci ne peut pas appartenir au m\u00eame foyer fiscal que l\u2019investisseur.<\/p>\n<p>Les avantages et dispositifs fiscaux de l&rsquo;investissement locatif ont \u00e9t\u00e9, au fil des ann\u00e9es, fonction des dates de mise en location, des dur\u00e9es de location, des caract\u00e9ristiques du logement, des publics cibl\u00e9s, des quartiers \u00e9ligibles, et, bien s\u00fbr, des objectifs politiques au moment de leur mise en place.<\/p>\n<p>Les lois et dispositifs ont \u00e9volu\u00e9. M\u00eame si certains ne sont plus ouverts, leurs effets se poursuivent encore parfois aujourd\u2019hui.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Malraux<\/strong><\/h2>\n<p>Mise en place en 1962, la loi Malraux est le premier des dispositifs fiscaux de l&rsquo;investissement locatif. Elle permet d\u2019acqu\u00e9rir un bien immobilier d\u2019exception \u00e0 restaurer et de b\u00e9n\u00e9ficier d\u2019une d\u00e9fiscalisation de 22% \u00e0 30 %, en fonction de la localisation du bien.<\/p>\n<p>La r\u00e9duction d\u2019imp\u00f4t se calcule sur le montant des travaux de restauration. La limite annuelle des d\u00e9penses prises en compte atteint aujourd\u2019hui 400 000 \u20ac pour une p\u00e9riode de 4 ann\u00e9es cons\u00e9cutives, pour tout permis de construire d\u00e9pos\u00e9 apr\u00e8s le 1er janvier 2017. Les sites concern\u00e9s sont :<\/p>\n<ul>\n<li>les Sites Patrimoniaux Remarquables (SPR) avec Plan de Sauvegarde et de Mise en Valeur (PSMV) approuv\u00e9. Ils donnent droit \u00e0 une d\u00e9fiscalisation pouvant atteindre 30 %. Aucune date limite n\u2019est fix\u00e9e pour ce dispositif.<\/li>\n<li>les immeubles situ\u00e9s dans les QAD (quartiers anciens d\u00e9grad\u00e9s) et les quartiers conventionn\u00e9s NPNRU &#8211; Anciens secteurs sauvegard\u00e9s. Ils donnent droit \u00e0 une d\u00e9fiscalisation (<strong>qui prend fin en 2024<\/strong>) pouvant atteindre 30 %.<\/li>\n<li>les immeubles situ\u00e9s dans des SPR avec Plan de Valorisation de l\u2019Architecture et du Patrimoine (PVAP) approuv\u00e9, ou dont le programme a \u00e9t\u00e9 d\u00e9clar\u00e9 d\u2019utilit\u00e9 publique. Ils donnent droit \u00e0 une r\u00e9duction d\u2019imp\u00f4t de l\u2019ordre de 22 %.<\/li>\n<li>les anciennes ZPPAUP et AAVAP et les zones pr\u00e9sentant une concentration \u00e9lev\u00e9e d\u2019habitations anciennes d\u00e9grad\u00e9.<\/li>\n<\/ul>\n<p>Il n\u2019y a pas de plafonds de loyer ni de plafond de ressources pour les locataires.<\/p>\n<p>Voir aussi notre article <a href=\"https:\/\/valoxy.org\/blog\/linvestissement-dans-les-monuments-historiques\/\">L\u2019investissement dans les monuments historiques<\/a>.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Perissol (1996-1999)<\/strong><\/h2>\n<p>Le dispositif \u00e9tait ouvert entre le 1er Janvier 1996 et le 31 Ao\u00fbt 1999 pour des logements neufs, en VEFA, ou les logements anciens r\u00e9habilit\u00e9s. Le contribuable pouvait d\u00e9duire de ses revenus fonciers 10 % du montant de l\u2019investissement pendant 4 ans, puis 2 % pendant les 5 ann\u00e9es suivantes. L\u2019amortissement pouvait se prolonger de 2% par an pendant 15 ans. (soit 80 % du montant investi sur 24 ans !)<\/p>\n<p>Durant cette p\u00e9riode, la d\u00e9duction forfaitaire pour charges diverses descendait \u00e0 6%, au lieu de 14% dans le r\u00e9gime commun.<\/p>\n<p>Le d\u00e9ficit foncier s&rsquo;imputait sur le revenu global \u00e0 hauteur de 15 300 \u20ac par an, avec report de l\u2019exc\u00e9dent sur les revenus fonciers des 10 ann\u00e9es suivantes.<\/p>\n<p>Les dispositifs Besson, Scellier, puis la loi Pinel depuis 2013 ont remplac\u00e9 la loi Perissol.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La Loi Demessine (1999)<\/strong><\/h2>\n<p>Son objectif \u00e9tait de stimuler l\u2019investissement immobilier et la construction dans des zones rurales d\u00e9sert\u00e9es et \u00e9conomiquement moroses, les ZRR.<\/p>\n<p>La loi visait l\u2019acquisition d\u2019un logement int\u00e9gr\u00e9 \u00e0 une r\u00e9sidence de tourisme ou un village r\u00e9sidentiel de tourisme dans ces zones. \u00c0 partir du 1er janvier 2005, le champ d\u2019application g\u00e9ographique a \u00e9t\u00e9 \u00e9tendu aux nouvelles zones rurales. (Marne-La-Vall\u00e9e, Melun-S\u00e9nart, l\u2019Isle-d\u2019Abeau, etc.)<\/p>\n<p>Avant 2005, pour un achat intervenu entre le 1er janvier 1999 et le 31 d\u00e9cembre 2004, l\u2019acqu\u00e9reur pouvait b\u00e9n\u00e9ficier d\u2019une r\u00e9duction d\u2019imp\u00f4ts de :<\/p>\n<ul>\n<li>25 % (calcul\u00e9e sur le prix d\u2019acquisition) \u00e9tal\u00e9e sur 4 ans pour les logements neufs ou en futur \u00e9tat d\u2019ach\u00e8vement,<\/li>\n<li>20 % \u00e9tal\u00e9e sur 4 ans sur le co\u00fbt des travaux de reconstruction, agrandissements, r\u00e9parations ou am\u00e9lioration,<\/li>\n<li>20 % r\u00e9partie sur 6 ans pour l\u2019acquisition ou la r\u00e9habilitation de logements anciens (\u00e0 compter du 1er janvier 2004)<\/li>\n<\/ul>\n<p>Apr\u00e8s 2005 (achats intervenus entre le 1er janvier 2005 et le 31 d\u00e9cembre 2012), l\u2019acqu\u00e9reur pouvait b\u00e9n\u00e9ficier d\u2019une r\u00e9duction d\u2019imp\u00f4ts de :<\/p>\n<ul>\n<li>25 % (ou 20 % pour la r\u00e9habilitation) \u00e9tal\u00e9e sur 6 ou 7 ans pour l\u2019acquisition de logements neufs ou en futur \u00e9tat d\u2019ach\u00e8vement ou pour la r\u00e9habilitation de logements anciens<\/li>\n<li>une r\u00e9duction d\u2019imp\u00f4t pour les travaux de r\u00e9paration, reconstruction, agrandissement\u2026 imputable \u00e0 l\u2019ann\u00e9e de r\u00e9alisation de ces travaux.<\/li>\n<\/ul>\n<p>Les avantages fiscaux Demessine ne pouvaient se cumuler avec<\/p>\n<ul>\n<li>le r\u00e9gime fiscal micro-foncier ou micro BIC (b\u00e9n\u00e9fices industriels et commerciaux)<\/li>\n<li>la d\u00e9duction de ces d\u00e9penses pour leur montant r\u00e9el sous la forme d\u2019une d\u00e9duction au titre de l\u2019amortissement<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>Le dispositif Besson<\/strong><\/h2>\n<p>Grand classique parmi les dispositifs fiscaux de l&rsquo;investissement locatif, sa mise en place date du 1er Janvier 1999.<\/p>\n<h4><strong>Besson \u201cancien\u201d<\/strong><\/h4>\n<p>Ce dispositif permettait de b\u00e9n\u00e9ficier d&rsquo;une r\u00e9duction des revenus fonciers \u00e0 hauteur de 26 % du montant de l\u2019investissement, et ainsi \u00eatre \u201cassimil\u00e9\u201d \u00e0 du d\u00e9ficit foncier, en plus des autres charges d\u00e9ductibles, dans la limite de 10 700 \u20ac annuels.<\/p>\n<p>Le dispositif Besson \u201cancien\u201d s&rsquo;appliquait aux logements mis en location entre le 1<sup>er<\/sup> janvier 1999 et le 30 septembre 2006. Il permettait aussi l\u2019attribution d\u2019un financement Action logement pour des travaux de r\u00e9novation qui repr\u00e9sentait entre 15 % et 50 % du co\u00fbt des travaux, plafonn\u00e9 \u00e0 12 800 \u20ac.\u00a0 Le dispositif \u00ab\u00a0Borloo ancien\u00a0\u00bb l&rsquo;a remplac\u00e9 le 1er octobre 2006.<\/p>\n<h4><strong>Besson \u201cneuf\u201d<\/strong><\/h4>\n<p>Il faut avoir acquis le bien immobilier (neuf ou r\u00e9habilit\u00e9 \u00e0 neuf) entre 1999 et avril 2023. Le dispositif Besson \u201cneuf\u201d offre une d\u00e9duction (r\u00e9duction de son revenu net imposable) de 8 % du montant de l\u2019investissement durant les 5 premi\u00e8res ann\u00e9es, puis de 2,5 % les 4, 7 et 10 ann\u00e9es suivantes. Ce qui repr\u00e9sente un amortissement qui peut aller jusqu\u2019\u00e0 50 % de la valeur du bien sur 9 ans, et jusque 65 % sur 15 ans. (Voir notre article <a href=\"https:\/\/valoxy.org\/blog\/quelles-differences-entre-deduction-reduction-et-credit-dimpot\/\">Quelles diff\u00e9rences entre d\u00e9duction, r\u00e9duction et cr\u00e9dit d\u2019imp\u00f4t ?<\/a>)<\/p>\n<p>En sus\u00a0 de l\u2019incitation fiscale, l\u2019investisseur peut d\u00e9duire ses charges d\u2019exploitation, et profiter d&rsquo;un abattement forfaitaire sur les loyers per\u00e7us \u00e0 hauteur de 6 %. La loi Cosse a remplac\u00e9 ce dispositif\u00a0 en 2016, et il a d\u00e9finitivement pris fin en 2019. Les bailleurs ayant opt\u00e9 pour ce dispositif ne peuvent plus b\u00e9n\u00e9ficier de ses effets \u00e0 partir du 1er janvier 2023.<\/p>\n<div class=\"encadre-style\">Attention ! Il ne faut pas confondre<strong> les dispositifs de d\u00e9fiscalisation Besson<\/strong> avec la<strong> L<\/strong><strong>oi Besson<\/strong><strong> (1990).<\/strong> Cette derni\u00e8re concerne le droit au logement des personnes d\u00e9favoris\u00e9es, et la cr\u00e9ation du Fonds de solidarit\u00e9 pour le logement (FSL), destin\u00e9 \u00e0 aider les personnes d\u00e9favoris\u00e9es \u00e0 acc\u00e9der \u00e0 un logement et \u00e0 y garantir leur maintien.<\/div>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>L<\/strong>e dispositif Lienemann (2002)<\/h2>\n<p id=\"Le_I_de_larticle_11_de_la_l_09\" class=\"paragraphe-western\">La loi de finances pour 2002 \u00a0avait compl\u00e9t\u00e9 le dispositif \u00ab Besson ancien \u00bb en y ajoutant une mesure destin\u00e9e \u00e0 favoriser la location de logements dans le secteur social : le dispositif \u00ab Lienemann \u00bb.<\/p>\n<p id=\"Lavantage_fiscal,_qui_est_s_010\" class=\"paragraphe-western\">L&rsquo;avantage fiscal, subordonn\u00e9 \u00e0 des conditions de loyers et de ressources plus strictes que pour les locations du secteur interm\u00e9diaire, prenait la forme, pour les logements neufs comme pour les logements anciens, d&rsquo;une majoration de 14 % \u00e0 60 % du taux de la d\u00e9duction forfaitaire pendant une p\u00e9riode de trois ans reconductible. Le dispositif \u00ab Lienemann \u00bb a \u00e9t\u00e9 supprim\u00e9 \u00e0 compter du 1<sup>er<\/sup> janvier 2005 et, \u00e0 l&rsquo;expiration du d\u00e9lai de trois ans, aucune prorogation ne pouvait plus \u00eatre effectu\u00e9e. A l&rsquo;issue de la p\u00e9riode de trois\u00a0ans en cours au 1<sup>er<\/sup> janvier 2005, le propri\u00e9taire pouvait b\u00e9n\u00e9ficier, sous certaines conditions, de la d\u00e9duction sp\u00e9cifique de 26 % pr\u00e9vue au j du 1\u00b0 du I de l&rsquo;article 31 du CGI.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Robien (2003)<\/strong><\/h2>\n<p>Le dispositif Robien se basait sur les m\u00eames principes que le Besson. Le choix du dispositif \u00e9tait irr\u00e9vocable, et devait s&rsquo;exercer lors du d\u00e9p\u00f4t de la d\u00e9claration de revenus de l\u2019ann\u00e9e<\/p>\n<ul>\n<li>d\u2019ach\u00e8vement de l&rsquo;immeuble,<\/li>\n<li>d&rsquo;acquisition du logement si elle est post\u00e9rieure<\/li>\n<li>d&rsquo;ach\u00e8vement des travaux dans le cas d&rsquo;une acquisition suivie de transformation.<\/li>\n<\/ul>\n<p>Il fallait louer le bien pendant neuf ans, renouvelables par p\u00e9riode de trois ans dans la limite de six ans.<\/p>\n<h4><strong>Dispositif Robien \u201cclassique\u201d (2003-2006)<\/strong><\/h4>\n<p>Il s\u2019applique aux investissements r\u00e9alis\u00e9s entre le 3 avril 2003 et le 31 ao\u00fbt 2006 pour l&rsquo;acquisition de logements neufs et la r\u00e9habilitation de logements anciens. Les propri\u00e9t\u00e9s se situent en zone urbaine,\u00a0 en m\u00e9tropole et dans les DOM.<\/p>\n<p>Le contribuable b\u00e9n\u00e9ficie d\u2019une d\u00e9duction d\u2019imp\u00f4ts (r\u00e9duction de la base imposable) de 8 % du montant de l&rsquo;investissement pendant une p\u00e9riode de 5 ans, puis 2,5\u00a0% pendant 4, 7 ou 10\u00a0ans. Soit un total maximum de 65 % du montant de l\u2019investissement. Le d\u00e9ficit foncier de l\u2019ann\u00e9e est imputable sur revenu global, dans la limite de 10 700 \u20ac.<\/p>\n<h4><strong>Dispositif Robien \u201crecentr\u00e9\u201d (2006-2009)<\/strong><\/h4>\n<p>Il s\u2019appliquait aux investissements r\u00e9alis\u00e9s entre le 1er septembre 2006 et le 31 d\u00e9cembre 2009. L\u2019investisseur b\u00e9n\u00e9ficiait d\u2019une d\u00e9duction d\u2019imp\u00f4ts (r\u00e9duction de la base imposable) de 6 % du montant de l&rsquo;investissement pendant une p\u00e9riode de 7 ans. Ensuite, la d\u00e9duction passait \u00e0 4 % pendant 2 ans, soit un total sur 9 ans de 50 % du montant de l\u2019investissement. Le dispositif Robien \u201crecentr\u00e9\u201d permettait aussi au bailleur de b\u00e9n\u00e9ficier d&rsquo;une d\u00e9duction des frais r\u00e9els, et non plus d&rsquo;un abattement forfaitaire.<\/p>\n<p>Enfin, lorsque le logement est situ\u00e9 en Zone de Revitalisation Rurale (ZRR), une d\u00e9duction sp\u00e9cifique de 26 % s\u2019appliquait sur les revenus fonciers.<\/p>\n<p>Le dispositif Robien n\u2019\u00e9tait pas cumulable avec les dispositifs de d\u00e9fiscalisation suivants\u00a0:<\/p>\n<ul>\n<li>la d\u00e9duction forfaitaire Cosse ancien<\/li>\n<li>la r\u00e9duction d\u2019imp\u00f4t Scellier<\/li>\n<li>l\u2019imputation des d\u00e9ficits fonciers sur les immeubles historiques ou d\u00e9coulant du dispositif ancien Malraux<\/li>\n<li>la r\u00e9duction d\u2019imp\u00f4t pour investissement par les particuliers dans les DOM<\/li>\n<li>le r\u00e9gime micro-foncier<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Borloo (2006)<\/strong><\/h2>\n<p><strong>Investissement immobilier dans le neuf ou populaire<\/strong><\/p>\n<p>Destin\u00e9 \u00e0 dynamiser l&rsquo;investissement immobilier locatif social, le dispositif fiscal Borloo concernait des investissements r\u00e9alis\u00e9s entre 2006 et 2009. Les conditions \u00e9taient similaires au dispositif Besson (voir plus haut).<\/p>\n<p><strong>Investissement immobilier dans l&rsquo;ancien<\/strong><\/p>\n<p>Le dispositif \u201cBorloo ancien\u201d ne concernait que des logements conventionn\u00e9s par l\u2019ANAH (agence nationale de l&rsquo;habitat). Ils devaient \u00eatre lou\u00e9s pendant une p\u00e9riode minimale de 6 ans (ou 9 ans en cas de subvention apport\u00e9e par l&rsquo;ANAH) \u00e0 titre d&rsquo;habitation principale, \u00e0 une cat\u00e9gorie de locataires tr\u00e8s encadr\u00e9e. Selon le\u00a0 type de convention sign\u00e9e avec l\u2019ANAH (interm\u00e9diaire, social, tr\u00e8s social), l&rsquo;acqu\u00e9reur pouvait b\u00e9n\u00e9ficier d&rsquo;un abattement sp\u00e9cifique sur ses revenus fonciers de 30 % \u00e0 60 %. Le dispositif \u201cBorloo ancien\u201d a \u00e9t\u00e9 remplac\u00e9 par la loi Cosse en 2016. Il ne s\u2019applique plus pour les prorogations de convention ANAH intervenant apr\u00e8s le 1<sup>er<\/sup> janvier 2024.<\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>Le dispositif Censi-Bouvard (2009)<\/strong><\/h2>\n<p>L\u2019amendement Censi-Bouvard visait \u00e0 donner aux loueurs de biens meubl\u00e9s non-professionnels <a class=\"mkd-pt-link\" href=\"https:\/\/valoxy.org\/blog\/location-meublee-non-professionnelle-lmnp\/\" target=\"_self\" rel=\"noopener\">(LMNP)<\/a>\u00a0les m\u00eames avantages fiscaux que la loi Scellier. La loi de finances 2019 a report\u00e9 la date limite pour en b\u00e9n\u00e9ficier \u00e0 la fin de l\u2019ann\u00e9e 2022.<\/p>\n<p>Le dispositif Censi-Bouvard visait les \u201cr\u00e9sidences services\u201d neuves ou r\u00e9nov\u00e9es (r\u00e9sidences \u00e9tudiantes, d\u2019affaires, pour personnes \u00e2g\u00e9es, handicap\u00e9es ou m\u00e9dicalis\u00e9es, r\u00e9sidences de tourisme class\u00e9es, ou foyers de vie ou d\u2019accueil de vie). Ses avantages \u00e9taient :<\/p>\n<ul>\n<li>une r\u00e9duction d\u2019imp\u00f4ts jusqu\u2019\u00e0 33 000 \u20ac, (3 666 \u20ac par an, pendant 9 ans) pouvant atteindre 11% de la valeur du bien HT,<\/li>\n<li>La r\u00e9cup\u00e9ration de la TVA de 20 % sur l\u2019investissement (sous certaines conditions)<\/li>\n<li>Une s\u00e9curisation des loyers pendant 11 ans par le gestionnaire, que le logement soit occup\u00e9 ou non.<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Cosse<\/strong><\/h2>\n<p>Le dispositif d&rsquo;investissement \u00ab\u00a0Louer abordable\u00a0\u00bb (dit \u201cLoi Cosse\u201d) a \u00e9t\u00e9 introduit par la loi de Finances rectificative pour 2016. Il s\u2019applique aux conventions d\u00e9pos\u00e9es avant le 1er mars 2022 ou prolong\u00e9es au-del\u00e0. Il remplace \u00e0 cette date les dispositifs Besson ancien et Borloo ancien, et l\u2019avantage fiscal est subordonn\u00e9 \u00e0 un conventionnement avec l\u2019ANAH. Le dispositif \u201cCosse ancien\u201d ne s\u2019applique plus pour les prorogations de convention ANAH intervenant apr\u00e8s le 1<sup>er<\/sup> janvier 2024.<\/p>\n<p>En 2022, le dispositif \u00e9volue et devient \u201cLoc\u2019Avantages\u201d (r\u00e9duction d\u2019imp\u00f4t pour les conventions sign\u00e9es \u00e0 partir du 1er mars 2022). L&rsquo;ancien dispositif reste toutefois en vigueur pour les conventions d\u00e9pos\u00e9es avant le <strong>28 f\u00e9vrier 2022.<\/strong><\/p>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Scellier (2009)<\/strong><\/h2>\n<p>L\u2019investissement locatif devait \u00eatre r\u00e9alis\u00e9 dans du neuf entre le 1er janvier 2009 et le 31 d\u00e9cembre 2012, en M\u00e9tropole et en Outre-mer. L\u2019avantage fiscal \u00e9tait fonction de zones g\u00e9ographiques caract\u00e9ris\u00e9es par un d\u00e9s\u00e9quilibre entre l\u2019offre et la demande de logements, et selon des plafonds de loyers.<\/p>\n<p>Nouveaut\u00e9 dans les dispositifs fiscaux de l&rsquo;investissement locatif, la loi Scellier\u00a0 int\u00e9grait aussi une limitation du nombre de biens acquis (une fois par an et par foyer fiscal), et un montant maximum (300 000 \u20ac) par op\u00e9ration r\u00e9alis\u00e9e.<\/p>\n<h4><strong>Scellier <\/strong><strong>\u201c<\/strong><strong>classique\u201d <\/strong><\/h4>\n<p>L&rsquo;investisseur b\u00e9n\u00e9ficiait d&rsquo;une <strong>r\u00e9duction d&rsquo;imp\u00f4t (et non plus d\u00e9duction\u2026)<\/strong>, calcul\u00e9e sur 9 ans de mani\u00e8re lin\u00e9aire :<\/p>\n<ul>\n<li>25 % du montant du bien pour une acquisition r\u00e9alis\u00e9e entre le 1er Janvier 2009 et le 31 D\u00e9cembre 2010,<\/li>\n<li>13 % pour une acquisition en 2011 (22 % s\u2019il s\u2019agit d\u2019un b\u00e2timent labellis\u00e9 BBC \u00ab b\u00e2timent basse consommation \u00bb),<\/li>\n<li>6 % pour une acquisition en 2012 pour les logements non-BBC acquis en 2012, ayant fait l\u2019objet d\u2019un permis de construire au plus tard le 31 d\u00e9cembre 2011, et 13 % s\u2019il s\u2019agit d\u2019un logement labellis\u00e9 BBC.<\/li>\n<\/ul>\n<h4><strong>\u00a0<\/strong><strong>Scellier <\/strong><strong>\u201c<\/strong><strong>social\u201d ou \u201cinterm\u00e9diaire\u201d<\/strong><\/h4>\n<p>Il permettait de b\u00e9n\u00e9ficier d&rsquo;une plus grande r\u00e9duction d&rsquo;imp\u00f4t \u00e0 condition de louer sur une plus longue p\u00e9riode (9, 12 ou 15 ans) un logement \u201cinterm\u00e9diaire\u201d (loyer plafonn\u00e9, \u00a0acc\u00e8s conditionn\u00e9 \u00e0 des seuils de revenus). Ce type de logement se situe entre le logement social et le logement locatif priv\u00e9 classique. Quand le logement neuf r\u00e9pond aux normes BBC, la r\u00e9duction d&rsquo;imp\u00f4t est maximale :<\/p>\n<ul>\n<li>13 % sur 9 ans,<\/li>\n<li>17 % sur 12 ans,<\/li>\n<li>21 % sur 15 ans<\/li>\n<\/ul>\n<p>Le bailleur b\u00e9n\u00e9ficiait \u00e9galement d&rsquo;une d\u00e9duction sp\u00e9cifique de 30 % \u00e0 valoir sur les revenus locatifs bruts durant toute la p\u00e9riode.<\/p>\n<p>Ce dispositif n&rsquo;est plus propos\u00e9 depuis le 1er\u00a0janvier 2013. Seules les personnes ayant investi\u00a0avant cette date peuvent encore b\u00e9n\u00e9ficier de l&rsquo;avantage fiscal, en cas de renouvellement de bail. Il \u00e9tait \u00e9galement possible de b\u00e9n\u00e9ficier de ce dispositif fiscal via les \u201cSCPI Scellier Social\u201d.<\/p>\n<h4><strong>Scellier <\/strong><strong>Outre-Mer<\/strong><\/h4>\n<p>Ce dispositif concernait tous les particuliers ayant achet\u00e9 un logement neuf (ou r\u00e9habilit\u00e9) entre le 27 mai 2009 et le 31 d\u00e9cembre 2012 dans les DOM\/TOM.<\/p>\n<p>L\u2019acqu\u00e9reur pouvait b\u00e9n\u00e9ficier de <strong>plusieurs avantages fiscaux<\/strong> :<\/p>\n<ul>\n<li>Une <strong>r\u00e9duction d<\/strong><strong>\u2019<\/strong><strong>imp\u00f4t de 24 %<\/strong> du prix du logement (dans la limite de 300 000 \u20ac) \u00e9tal\u00e9e sur 9 ans.<\/li>\n<li>Un<strong> abattement fiscal de 30 %<\/strong> sur les loyers per\u00e7<\/li>\n<li>Une <strong>r\u00e9duction d<\/strong><strong>\u2019<\/strong><strong>imp\u00f4t compl\u00e9mentaire<\/strong> de 8 % pour un engagement de location de 6 ann\u00e9es suppl\u00e9mentaires au terme des 9 ans, soit une r\u00e9duction totale de 32 % sur 15 ans.<\/li>\n<li>La possibilit\u00e9 d\u2019<strong>imputer les d\u00e9ficits fonciers<\/strong> pendant la p\u00e9riode de d\u00e9fiscalisation.<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Duflot<\/strong><\/h2>\n<p>La loi Duflot a succ\u00e9d\u00e9 \u00e0 la loi Scellier au 1er\u00a0janvier\u00a02013. La dur\u00e9e totale du dispositif est de 12 ans. L\u2019investisseur b\u00e9n\u00e9ficie d\u2019une r\u00e9duction de l&rsquo;imp\u00f4t \u00e0 hauteur de 2 % du prix de l&rsquo;acquisition pendant les 9 premi\u00e8res ann\u00e9es, et de 1 % les 3 ann\u00e9es suivantes. Comme pour le dispositif Scellier, le plafond du prix d&rsquo;achat \u00e9tait de 300 000 \u20ac par an, auquel s&rsquo;ajoutait un plafonnement au m\u00e8tre carr\u00e9 \u00e0 hauteur de 5 500 \u20ac. La r\u00e9duction d&rsquo;imp\u00f4t concerne les logements :<\/p>\n<ul>\n<li>\u00a0neufs, ou en \u00e9tat futur d\u2019ach\u00e8vement, ou que l\u2019on fait construire,<\/li>\n<li>anciens \u00e0 r\u00e9nover dont la r\u00e9novation repr\u00e9sente au moins <strong>25\u00a0%<\/strong> du co\u00fbt total de l\u2019op\u00e9ration, ceux faisant l&rsquo;objet de travaux de r\u00e9habilitation,<\/li>\n<li>les locaux transform\u00e9s en habitation.<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>La loi Pinel (2014)<\/strong><\/h2>\n<p>La loi Pinel a remplac\u00e9 la loi Duflot au 1er septembre 2014. Elle s\u2019applique aux op\u00e9rations d&rsquo;investissement locatif r\u00e9alis\u00e9es jusqu\u2019au 31 D\u00e9cembre 2024. Ses caract\u00e9ristiques sont les m\u00eames que pour le Duflot. (Voir notre article <a href=\"https:\/\/valoxy.org\/blog\/reduction-impot-pinel\/\">La r\u00e9duction d\u2019imp\u00f4t pour investissement locatif : le dispositif Pinel<\/a>). Cependant, depuis le 1<sup>er<\/sup> janvier 2021, la r\u00e9duction ne concerne <strong>plus que les logements situ\u00e9s dans un immeuble collectif<\/strong>. Le logement individuel et pavillonnaire en est exclus.<\/p>\n<p>Le taux de r\u00e9duction d\u2019imp\u00f4t est de 2 % par an pendant les 6 premi\u00e8res ann\u00e9es, 2 % par an pendant les 3 ann\u00e9es suivantes, et 1 % par an pendant les 3 derni\u00e8res ann\u00e9es.<\/p>\n<p>Les acquisitions r\u00e9alis\u00e9es \u00e0 partir de 2023 verront leurs taux progressivement r\u00e9duits, \u00e0 l\u2019exception des acquisitions de logements situ\u00e9s dans un quartier prioritaire de la politique de la ville ou qui respectent un niveau \u00e9lev\u00e9 de qualit\u00e9 (dispositif Pinel+) :<\/p>\n<ul>\n<li>En 2023, les taux seront de 10,5% pour un engagement de location de 6 ans, 15\u00a0% pour 9 ans, et 17,5\u00a0% pour 12 ans.<\/li>\n<li>En 2024 les taux seront de 9\u00a0% pour un engagement de location de 6 ans, 12\u00a0% pour 9 ans, et 14\u00a0% pour 12 ans.<\/li>\n<\/ul>\n<h2><span style=\"color: #c1d72e;\">\u2014 <\/span><strong>Dispositif fiscal Denormandie (2019)<\/strong><\/h2>\n<p>Dernier n\u00e9 des dispositifs fiscaux de l&rsquo;investissement locatif, le dispositif \u201cDenormandie\u201d concerne la r\u00e9novation de logements anciens ou la transformation de locaux en usage d\u2019habitation. Il a \u00e9t\u00e9 ouvert pour les investissements r\u00e9alis\u00e9s entre le 28 mars 2019 et le 31 d\u00e9cembre 2023. Les travaux doivent repr\u00e9senter au moins <strong>25\u00a0%<\/strong> du co\u00fbt total de l\u2019op\u00e9ration, et inclure :<\/p>\n<ul>\n<li>des travaux d\u2019am\u00e9lioration d\u2019au moins 20\u00a0% de la performance \u00e9nerg\u00e9tique (30\u00a0% pour les logements individuels),<\/li>\n<li>au minimum 2 types de travaux parmi le changement de chaudi\u00e8re, l&rsquo;isolation des combles, l&rsquo;isolation des murs, le changement de production d&rsquo;eau chaude, et l&rsquo;isolation des fen\u00eatres,<\/li>\n<li>la cr\u00e9ation de surface habitable nouvelle (y compris balcon, terrasse ou garage).<\/li>\n<\/ul>\n<p>Le logement doit se situer dans des communes<\/p>\n<ul>\n<li>dont le besoin de r\u00e9habilitation de l&rsquo;habitat est important,<\/li>\n<li>ou qui se trouvent en zone labellis\u00e9e <em>C\u0153ur de ville, <\/em><\/li>\n<li>ou encore qui ont pass\u00e9 une convention d\u2019op\u00e9ration de revitalisation de territoire (ORT).<\/li>\n<\/ul>\n<p>Sous condition du revenu fiscal de r\u00e9f\u00e9rence du locataire, la r\u00e9duction d&rsquo;imp\u00f4t \u00ab Denormandie\u00a0\u00bb s\u2019\u00e9l\u00e8ve \u00e0 :<\/p>\n<ul>\n<li>12\u00a0% du prix du bien (achat plus travaux de r\u00e9novation) pour une p\u00e9riode de location de six\u00a0ans,<\/li>\n<li>18 % pour une p\u00e9riode de location de neuf\u00a0ans,<\/li>\n<li>21 % pour une p\u00e9riode de location de douze\u00a0ans.<\/li>\n<\/ul>\n<div class=\"encadre-style\">Besoin de conseils pour la gestion et l&rsquo;optimisation de votre patrimoine ? Contactez\u00a0 Valo&rsquo;Patrimoine et nos experts ! Ils vous accompagneront avec exigence et en toute ind\u00e9pendance.<\/p>\n<p><\/div>\n<p>Cet article sur les dispositifs fiscaux de l&rsquo;investissement locatif vous a int\u00e9ress\u00e9 ? Dites-le nous dans les commentaires ci-apr\u00e8s ! Retrouvez \u00e9galement nos autres articles sur le blog de Valoxy :<\/p>\n<ul>\n<li><a href=\"https:\/\/valoxy.org\/blog\/pensez-micro-foncier-declarer-vos-loyers\/\">Le Micro foncier<\/a><\/li>\n<li><a href=\"https:\/\/valoxy.org\/blog\/la-taxe-damenagement\/\">La taxe d\u2019am\u00e9nagement<\/a><\/li>\n<li><a href=\"https:\/\/valoxy.org\/blog\/pret-locatif-social-ou-pls\/\">Le pr\u00eat locatif social (PLS)<\/a><\/li>\n<li><a href=\"https:\/\/valoxy.org\/blog\/projet-de-loi-de-finances-2024\/\">Le projet de loi de finances 2024<\/a><\/li>\n<li><a href=\"https:\/\/valoxy.org\/blog\/limpot-sur-la-fortune-immobiliere-ifi\/\">L\u2019imp\u00f4t sur la fortune immobili\u00e8re (IFI)<\/a><\/li>\n<li><a href=\"https:\/\/valoxy.org\/blog\/location-meublee-professionnelle-non-professionnelle\/\">La location meubl\u00e9e : professionnelle ou non-professionnelle ?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>De nombreux dispositifs fiscaux de l&rsquo;investissement locatif existent en France. Ils permettent d\u2019optimiser certains investissements immobiliers. Leur objectif\u00a0 ? Utiliser l&rsquo;accession \u00e0 la propri\u00e9t\u00e9 immobili\u00e8re locative pour alimenter (et dynamiser) le march\u00e9 immobilier locatif. Valoxy, cabinet d\u2019expertise comptable dans les&#8230;<\/p>\n","protected":false},"author":1,"featured_media":63833,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,6],"tags":[],"class_list":["post-63832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalite","category-patrimoine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable<\/title>\n<meta name=\"description\" content=\"De nombreux dispositifs fiscaux de l&#039;investissement locatif permettent d\u2019optimiser les investissements immobiliers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable\" \/>\n<meta property=\"og:description\" content=\"De nombreux dispositifs fiscaux de l&#039;investissement locatif permettent d\u2019optimiser les investissements immobiliers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Valoxy - Expertise comptable\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Valoxy\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T06:30:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T08:43:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expert-comptable Valoxy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expert-comptable Valoxy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\"},\"author\":{\"name\":\"Expert-comptable Valoxy\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/d285f250195f45509ceac046366fcc4a\"},\"headline\":\"Dispositifs fiscaux de l\u2019investissement locatif\",\"datePublished\":\"2023-10-17T06:30:40+00:00\",\"dateModified\":\"2026-01-27T08:43:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\"},\"wordCount\":3338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg\",\"articleSection\":[\"Fiscalit\u00e9\",\"Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\",\"url\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\",\"name\":\"Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable\",\"isPartOf\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg\",\"datePublished\":\"2023-10-17T06:30:40+00:00\",\"dateModified\":\"2026-01-27T08:43:37+00:00\",\"description\":\"De nombreux dispositifs fiscaux de l'investissement locatif permettent d\u2019optimiser les investissements immobiliers.\",\"breadcrumb\":{\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage\",\"url\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg\",\"contentUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Avantages Fiscaux de l'Investissement Locatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/valoxy.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dispositifs fiscaux de l\u2019investissement locatif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valoxy.org\/blog\/#website\",\"url\":\"https:\/\/valoxy.org\/blog\/\",\"name\":\"Blog Valoxy\",\"description\":\"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise\",\"publisher\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\"},\"alternateName\":\"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valoxy.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valoxy.org\/blog\/#organization\",\"name\":\"Blog Valoxy\",\"url\":\"https:\/\/valoxy.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png\",\"contentUrl\":\"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png\",\"width\":266,\"height\":100,\"caption\":\"Blog Valoxy\"},\"image\":{\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Valoxy\",\"https:\/\/www.linkedin.com\/company\/valoxy\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/d285f250195f45509ceac046366fcc4a\",\"name\":\"Expert-comptable Valoxy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/valoxy.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e8d0ed8d4c117e5d77ddb78bbcab5f6b5841424c6b20eeaafcfd8741ef2aa2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e8d0ed8d4c117e5d77ddb78bbcab5f6b5841424c6b20eeaafcfd8741ef2aa2c?s=96&d=mm&r=g\",\"caption\":\"Expert-comptable Valoxy\"},\"sameAs\":[\"https:\/\/valoxy.org\/blog\"],\"url\":\"https:\/\/valoxy.org\/blog\/author\/ceo-valoxy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable","description":"De nombreux dispositifs fiscaux de l'investissement locatif permettent d\u2019optimiser les investissements immobiliers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/","og_locale":"fr_FR","og_type":"article","og_title":"Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable","og_description":"De nombreux dispositifs fiscaux de l'investissement locatif permettent d\u2019optimiser les investissements immobiliers.","og_url":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/","og_site_name":"Blog Valoxy - Expertise comptable","article_publisher":"https:\/\/www.facebook.com\/Valoxy","article_published_time":"2023-10-17T06:30:40+00:00","article_modified_time":"2026-01-27T08:43:37+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg","type":"image\/jpeg"}],"author":"Expert-comptable Valoxy","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Expert-comptable Valoxy","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#article","isPartOf":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/"},"author":{"name":"Expert-comptable Valoxy","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/d285f250195f45509ceac046366fcc4a"},"headline":"Dispositifs fiscaux de l\u2019investissement locatif","datePublished":"2023-10-17T06:30:40+00:00","dateModified":"2026-01-27T08:43:37+00:00","mainEntityOfPage":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/"},"wordCount":3338,"commentCount":0,"publisher":{"@id":"https:\/\/valoxy.org\/blog\/#organization"},"image":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage"},"thumbnailUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg","articleSection":["Fiscalit\u00e9","Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/","url":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/","name":"Dispositifs fiscaux de l\u2019investissement locatif | Blog Valoxy - Expertise comptable","isPartOf":{"@id":"https:\/\/valoxy.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage"},"image":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage"},"thumbnailUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg","datePublished":"2023-10-17T06:30:40+00:00","dateModified":"2026-01-27T08:43:37+00:00","description":"De nombreux dispositifs fiscaux de l'investissement locatif permettent d\u2019optimiser les investissements immobiliers.","breadcrumb":{"@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#primaryimage","url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg","contentUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2023\/10\/avantages-fiscaux-de-linvestissement-locatif-scaled-1.jpg","width":1707,"height":2560,"caption":"Avantages Fiscaux de l'Investissement Locatif"},{"@type":"BreadcrumbList","@id":"https:\/\/valoxy.org\/blog\/dispositifs-fiscaux-de-linvestissement-locatif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/valoxy.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Dispositifs fiscaux de l\u2019investissement locatif"}]},{"@type":"WebSite","@id":"https:\/\/valoxy.org\/blog\/#website","url":"https:\/\/valoxy.org\/blog\/","name":"Blog Valoxy","description":"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise","publisher":{"@id":"https:\/\/valoxy.org\/blog\/#organization"},"alternateName":"Le Blog Valoxy, ce sont plus de 1500 articles sur toute l&#039;actualit\u00e9 comptable, juridique, fiscale, et la gestion d&#039;entreprise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valoxy.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/valoxy.org\/blog\/#organization","name":"Blog Valoxy","url":"https:\/\/valoxy.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png","contentUrl":"https:\/\/valoxy.org\/blog\/wp-content\/uploads\/2024\/05\/cropped-blog-valoxy-logo-300x118-2.png","width":266,"height":100,"caption":"Blog Valoxy"},"image":{"@id":"https:\/\/valoxy.org\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Valoxy","https:\/\/www.linkedin.com\/company\/valoxy"]},{"@type":"Person","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/d285f250195f45509ceac046366fcc4a","name":"Expert-comptable Valoxy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/valoxy.org\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5e8d0ed8d4c117e5d77ddb78bbcab5f6b5841424c6b20eeaafcfd8741ef2aa2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e8d0ed8d4c117e5d77ddb78bbcab5f6b5841424c6b20eeaafcfd8741ef2aa2c?s=96&d=mm&r=g","caption":"Expert-comptable Valoxy"},"sameAs":["https:\/\/valoxy.org\/blog"],"url":"https:\/\/valoxy.org\/blog\/author\/ceo-valoxy\/"}]}},"_links":{"self":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/63832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/comments?post=63832"}],"version-history":[{"count":4,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/63832\/revisions"}],"predecessor-version":[{"id":73130,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/posts\/63832\/revisions\/73130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/media\/63833"}],"wp:attachment":[{"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/media?parent=63832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/categories?post=63832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valoxy.org\/blog\/wp-json\/wp\/v2\/tags?post=63832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}